{"id":19408,"date":"2026-03-16T15:39:18","date_gmt":"2026-03-16T14:39:18","guid":{"rendered":"https:\/\/erbeticino.ch\/bio-bergkraeutertee-mit-verbene\/"},"modified":"2026-03-18T09:43:31","modified_gmt":"2026-03-18T08:43:31","slug":"bio-bergkraeutertee-mit-verbene","status":"publish","type":"product","link":"https:\/\/erbeticino.ch\/de\/bio-bergkraeutertee-mit-verbene\/","title":{"rendered":"Bio-Bergkr\u00e4utertee mit Verbene"},"content":{"rendered":"<p>Zutaten:<\/p>\n<ul>\n<li>Verbene<\/li>\n<li>Blaue Kornblume<\/li>\n<\/ul>\n<p>Die Kultur des Kr\u00e4utertees ist inzwischen zu einem echten Ritual geworden. Diese feinen Kr\u00e4utermischungen werden in eleganten pyramidenf\u00f6rmigen Teebeuteln verpackt und machen die Zubereitung des Tees auch optisch zu einem angenehmen Erlebnis. <\/p>\n<p>Portionsgr\u00f6\u00dfe: 1,5 g (15 pyramidenf\u00f6rmige Teebeutel)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zutaten: Verbene Blaue Kornblume Die Kultur des Kr\u00e4utertees ist inzwischen zu einem echten Ritual geworden. Diese feinen Kr\u00e4utermischungen werden in eleganten pyramidenf\u00f6rmigen Teebeuteln verpackt und machen die Zubereitung des Tees auch optisch zu einem angenehmen Erlebnis. Portionsgr\u00f6\u00dfe: 1,5 g (15 pyramidenf\u00f6rmige Teebeutel)<\/p>\n","protected":false},"featured_media":19407,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[166],"product_tag":[],"class_list":{"0":"post-19408","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-krautertees","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/erbeticino.ch\/de\/wp-json\/wp\/v2\/product\/19408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erbeticino.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/erbeticino.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/erbeticino.ch\/de\/wp-json\/wp\/v2\/comments?post=19408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/erbeticino.ch\/de\/wp-json\/wp\/v2\/media\/19407"}],"wp:attachment":[{"href":"https:\/\/erbeticino.ch\/de\/wp-json\/wp\/v2\/media?parent=19408"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/erbeticino.ch\/de\/wp-json\/wp\/v2\/product_brand?post=19408"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/erbeticino.ch\/de\/wp-json\/wp\/v2\/product_cat?post=19408"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/erbeticino.ch\/de\/wp-json\/wp\/v2\/product_tag?post=19408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}